{"id":2643,"date":"2021-01-20T12:58:28","date_gmt":"2021-01-20T11:58:28","guid":{"rendered":"https:\/\/energystoragesolutions.com\/politica-de-privacidad\/"},"modified":"2024-11-14T10:57:09","modified_gmt":"2024-11-14T09:57:09","slug":"politica-de-privacidad","status":"publish","type":"page","link":"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/","title":{"rendered":"Pol\u00edtica de Privacidad"},"content":{"rendered":"<div class=\"fusion-fullwidth fullwidth-box fusion-builder-row-1 fusion-parallax-none nonhundred-percent-fullwidth non-hundred-percent-height-scrolling\" style=\"background-color: rgba(255,255,255,0);background-image: url(&quot;https:\/\/energystoragesolutions.com\/wp-content\/uploads\/2018\/12\/BACKGROUND-E22-SERVICES.png&quot;);background-position: center center;background-repeat: no-repeat;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;margin-bottom: 0px;margin-top: 0px;border-width: 0px 0px 0px 0px;border-color:#eae9e9;border-style:solid;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;\" ><div class=\"fusion-builder-row fusion-row\"><div class=\"fusion-layout-column fusion_builder_column fusion-builder-column-0 fusion_builder_column_1_1 1_1 fusion-one-full fusion-column-first fusion-column-last\" style=\"margin-top:180px;margin-bottom:20px;\"><div class=\"fusion-column-wrapper fusion-flex-column-wrapper-legacy\" style=\"background-position:left top;background-repeat:no-repeat;-webkit-background-size:cover;-moz-background-size:cover;-o-background-size:cover;background-size:cover;background-color:rgba(50,101,126,0.8);padding: 50px 50px 50px 50px;\"><div class=\"fusion-text fusion-text-1\"><h1><span style=\"color: #ff9900;\"><strong>Pol\u00edtica de Privacidad<\/strong><\/span><\/h1>\n<p><span style=\"color: #ffffff;\"><strong>Fecha \u00faltima actualizaci\u00f3n: noviembre 2024<\/strong><\/span><\/p>\n<p><span style=\"color: #ff9900;\"><strong>Informaci\u00f3n b\u00e1sica sobre Protecci\u00f3n de Datos<\/strong><\/span><\/p>\n<table width=\"1278\">\n<tbody>\n<tr>\n<td width=\"293\"><span style=\"color: #ffffff;\">Responsable<\/span><\/td>\n<td width=\"985\"><span style=\"color: #ffffff;\">Energy Storage Solutions, S.L.U., (en adelante, \u201cE22\u201d)<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"293\"><span style=\"color: #ffffff;\">Contacto protecci\u00f3n de datos<\/span><\/td>\n<td width=\"985\"><span style=\"color: #ffffff;\">contact@energystoragesolutions.com\u00a0<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"293\"><span style=\"color: #ffffff;\">Sitio Web<\/span><\/td>\n<td width=\"985\"><span style=\"color: #ffffff;\">www.energystoragesolutions.com<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"293\"><span style=\"color: #ffffff;\">Finalidad<\/span><\/td>\n<td width=\"985\"><span style=\"color: #ffffff;\">Responder consultas, sugerencias, reclamaciones o solicitudes de informaci\u00f3n, o en su caso, gestionar y valorar candidaturas recibidas a trav\u00e9s del apartado \u201cContact\u201d.<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"293\"><span style=\"color: #ffffff;\">Legitimaci\u00f3n<\/span><\/td>\n<td width=\"985\"><span style=\"color: #ffffff;\">Consentimiento del interesado.<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"293\"><span style=\"color: #ffffff;\">Destinatarios<\/span><\/td>\n<td width=\"985\"><span style=\"color: #ffffff;\">Compartiremos sus datos personales con prestadores de servicios que nos ayudan o dan soporte, o con aquellos con quienes tengamos una obligaci\u00f3n legal.<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"293\"><span style=\"color: #ffffff;\">Derechos del usuario<\/span><\/td>\n<td width=\"985\"><span style=\"color: #ffffff;\">Tiene derecho a acceder, rectificar, suprimir, oponerte, solicitar la limitaci\u00f3n portabilidad o a no ser objeto de decisiones individuales automatizadas de tus datos personales, como te explicamos en detalle m\u00e1s abajo. Frente a cualquier vulneraci\u00f3n de sus derechos, especialmente cuando no haya obtenido satisfacci\u00f3n en su ejercicio, un interesado puede presentar una reclamaci\u00f3n ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (datos de contacto accesibles en <a href=\"http:\/\/www.aepd.es\">www.aepd.es<\/a>).<\/span><\/td>\n<\/tr>\n<tr>\n<td width=\"293\"><span style=\"color: #ffffff;\">Informaci\u00f3n adicional<\/span><\/td>\n<td width=\"985\"><span style=\"color: #ffffff;\"><a href=\"https:\/\/energystoragesolutions.com\/es\/politica-de-cookies\/\">Pol\u00edtica de cookies<\/a><\/span><\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p><span style=\"color: #ffffff;\">www.energystoragesolutions.com (en adelante, el \u201c<strong>Sitio Web<\/strong>\u201d) es operado por ENERGY STORAGE SOLUTIONS, S.L., (en adelante, \u201c<strong>nosotros<\/strong>\u201d).<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Esta pol\u00edtica de privacidad (en adelante la \u201c<strong>Pol\u00edtica<\/strong>\u201d) proporciona una descripci\u00f3n general de nuestras pr\u00e1cticas relativas al uso de informaci\u00f3n de car\u00e1cter personal que se recoge en el Sitio Web o que se trata en el marco de los servicios prestados en el Sitio Web (en adelante, los \u201c<strong>Servicios<\/strong>\u201d).<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Tenga en cuenta que la Pol\u00edtica es de aplicaci\u00f3n con independencia del dispositivo que utilice para acceder al Sitio Web o utilizar los Servicios, ya sea un tel\u00e9fono m\u00f3vil, una tableta, un ordenador u otro dispositivo.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Es importante que lea la Pol\u00edtica con detenimiento porque cada vez que acceda al Sitio Web y utilice nuestros Servicios, estar\u00e1 aceptando las pr\u00e1cticas que describimos en la misma. Si no acepta las pr\u00e1cticas descritas en la Pol\u00edtica, no debe acceder al Sitio Web ni utilizar los Servicios.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Tambi\u00e9n es importante que consulte con frecuencia la Pol\u00edtica por si se ha actualizado. Al acceder al Sitio Web o utilizar nuestros Servicios despu\u00e9s de que hayamos actualizado la Pol\u00edtica, usted estar\u00e1 aceptando la nueva versi\u00f3n de la misma. La versi\u00f3n m\u00e1s actualizada de la Pol\u00edtica siempre estar\u00e1 disponible aqu\u00ed. Puede comprobar la \u201cfecha de entrada en vigor\u201d publicada en la parte superior para comprobar cu\u00e1ndo se actualiz\u00f3 por \u00faltima vez.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Este Sitio Web no est\u00e1 destinado a menores de 18 a\u00f1os de manera que no solicitamos ni recabamos de manera intencionada datos relativos a menores de edad.<\/span><\/p>\n<p><span style=\"color: #ff9900;\">\u00bfQui\u00e9n es el Responsable del tratamiento de tus datos?<\/span><\/p>\n<ul>\n<li><span style=\"color: #ffffff;\">Identidad: ENERGY STORAGE SOLUTIONS, S.L., (CIF B87821880).<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Direcci\u00f3n postal: Avenida de Transici\u00f3n Espa\u00f1ola, 32, Parque Empresarial Omega, Edificio A, 28108, Alcobendas, Madrid.<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Tel\u00e9fono: (+34) 917364248<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Correo electr\u00f3nico:\u00a0contact@energystoragesolutions.com<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Inscrita en el Registro Mercantil de Madrid:\u00a0al Tomo 36023, Libro 0, Folio 173, Secci\u00f3n 8, y Hoja M 647293.<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #ff9900;\">\u00bfQu\u00e9 tipo de datos personales recabamos y c\u00f3mo los hemos obtenido?<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Las categor\u00edas de datos personales que recogemos de los usuarios del Sitio Web:<\/span><\/p>\n<ul>\n<li><span style=\"color: #ffffff;\">Nombre<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Direcci\u00f3n de correo electr\u00f3nico<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Tel\u00e9fono<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Datos personales que, en su caso, se env\u00eden por el usuario, relativos a su perfil profesional, con la finalidad de participar en nuestros procesos de selecci\u00f3n<\/span><\/li>\n<li><span style=\"color: #ffffff;\">Datos de conexi\u00f3n y navegaci\u00f3n<\/span><\/li>\n<\/ul>\n<p><span style=\"color: #ffffff;\">Todos los datos arriba mencionados los hemos obtenido directamente del usuario al completar el formulario de solicitud de informaci\u00f3n en el Sitio Web.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">El Sitio Web utiliza cookies que recogen y utilizan informaci\u00f3n de conformidad con lo establecido en la Pol\u00edtica de Cookies.<\/span><\/p>\n<p><span style=\"color: #ff9900;\">\u00bfCon qu\u00e9 finalidad tratamos tus datos personales?<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Los datos podr\u00e1n ser tratados exclusivamente con la finalidad de responder sus consultas, sugerencias, reclamaciones o solicitudes de informaci\u00f3n.<\/span><\/p>\n<p><span style=\"color: #ff9900;\">\u00bfDurante cu\u00e1nto tiempo trataremos tus datos?<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Los datos que nos facilite se conservar\u00e1n durante el periodo de tiempo necesario para cumplir con su solicitud y, posteriormente, los datos personales \u00fanicamente se mantendr\u00e1n en los t\u00e9rminos previstos para cumplir con las obligaciones aplicables.<\/span><\/p>\n<p><span style=\"color: #ff9900;\">\u00bfCu\u00e1l es la legitimaci\u00f3n para el tratamiento de tus datos?<\/span><\/p>\n<p><span style=\"color: #ffffff;\">La base legal para el tratamiento de los datos de car\u00e1cter personal es el consentimiento del usuario, otorgado mediante el env\u00edo de la solicitud de informaci\u00f3n. Dicho consentimiento puede revocarse en cualquier momento. Asimismo, en su caso, la base legal para el tratamiento de los datos de car\u00e1cter personal derivados de la recepci\u00f3n de candidaturas a trav\u00e9s del apartado \u201cContact\u201d, en el marco de posibles procesos de selecci\u00f3n, es la aplicaci\u00f3n de medidas contractuales.<\/span><\/p>\n<p><span style=\"color: #ff9900;\">\u00bfA qu\u00e9 destinatarios se comunicar\u00e1n tus datos?<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Podemos compartir la informaci\u00f3n proporcionada o generada en nuestro Sitio Web con proveedores de servicios que prestan servicios en nuestro nombre o cuenta. Dichos terceros han sido cuidadosamente seleccionados y hemos suscrito con \u00e9stos los correspondientes contratos de encargado del tratamiento para garantizar que los datos se tratan de conformidad con lo dispuesto en la normativa sobre protecci\u00f3n de datos y en la presente Pol\u00edtica.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Igualmente, podemos facilitar los datos personales cuando exista una obligaci\u00f3n legal que nos lo exija.<\/span><\/p>\n<p><span style=\"color: #ff9900;\">Google reCAPTCHA<\/span><\/p>\n<p><span style=\"color: #ffffff;\">En nuestro Sitio Web utilizamos \u201cGoogle reCAPTCHA\u201d (en adelante \u201creCAPTCHA\u201d). El proveedor es Google Ireland Limited, Gordon House, Barrow Street, Dublin 4, Irlanda (\u201cGoogle\u201d).<\/span><\/p>\n<p><span style=\"color: #ffffff;\">El prop\u00f3sito de reCAPTCHA es comprobar si la entrada de datos en nuestro Sitio Web (por ejemplo, en un formulario de contacto) es realizada por una persona o por un programa automatizado. Para este prop\u00f3sito, reCAPTCHA analiza el comportamiento del visitante del Sitio Web en funci\u00f3n de varias caracter\u00edsticas. Este an\u00e1lisis se inicia autom\u00e1ticamente en cuanto el visitante entra en el Sitio Web. Para el an\u00e1lisis, reCAPTCHA eval\u00faa informaci\u00f3n diversa (por ejemplo, la direcci\u00f3n IP, la duraci\u00f3n de la estancia del visitante en el Sitio Web o los movimientos del rat\u00f3n realizados por el usuario). Los datos recogidos durante el an\u00e1lisis se env\u00edan a Google.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Los an\u00e1lisis reCAPTCHA se ejecutan completamente en segundo plano. No se informa a los visitantes del Sitio Web de que se est\u00e1 llevando a cabo un an\u00e1lisis.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">El tratamiento de datos se realiza exclusivamente sobre la base de nuestro inter\u00e9s leg\u00edtimo de proteger el Sitio Web y garantizar su seguridad.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Encontrar\u00e1 m\u00e1s informaci\u00f3n sobre el servicio reCAPTCHA de Google y la pol\u00edtica de privacidad de Google en los siguientes enlaces:\u00a0<a style=\"color: #ffffff;\" href=\"https:\/\/policies.google.com\/privacy?hl=es\">https:\/\/policies.google.com\/privacy?hl=es<\/a>\u00a0y\u00a0<a style=\"color: #ffffff;\" href=\"https:\/\/www.google.com\/recaptcha\/intro\/android.html\">https:\/\/www.google.com\/recaptcha\/intro\/android.html<\/a>.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">El Sitio Web incluye plugins que permiten realizar determinadas acciones en redes sociales de terceros Estos plugins se indican mediante el logotipo de la red social correspondiente. Si el usuario acepta esos plugins, el contenido correspondiente se transferir\u00e1 a la red social pertinente. El usuario puede encontrar informaci\u00f3n acerca del funcionamiento de estos plugins y la forma en que tratan su informaci\u00f3n en las pol\u00edticas de protecci\u00f3n de datos personales de estas redes sociales. Si no desea que estas redes sociales recopilen sus datos, no deber\u00e1 aceptar el plugin y deber\u00e1 salirse de su cuenta antes de navegar por el Sitio Web.<\/span><\/p>\n<p><span style=\"color: #ff9900;\">\u00bfCu\u00e1les son los derechos del usuario cuando nos facilita sus datos personales?<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Cualquier persona tiene derecho a obtener confirmaci\u00f3n sobre si estamos tratando datos personales que le conciernan, o no.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">En concreto, los interesados pueden solicitar el derecho de acceso a sus datos personales, as\u00ed como a recibirlos en un formato com\u00fan y lectura mecanizada si el tratamiento se efect\u00faa por medios electr\u00f3nicos (derecho de portabilidad).<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Asimismo, las personas interesadas pueden solicitar el derecho de rectificaci\u00f3n de los datos inexactos o, en su caso, solicitar su supresi\u00f3n cuando, entre otros motivos, los datos ya no sean necesarios para los fines para los que fueron recogidos.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">En las condiciones previstas en la normativa aplicable, los interesados podr\u00e1n solicitar la limitaci\u00f3n del tratamiento de sus datos.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">En determinadas circunstancias y por motivos relacionados con su situaci\u00f3n particular, los interesados podr\u00e1n ejercitar su derecho a oponerse al tratamiento de sus datos. Si han otorgado el consentimiento para alguna finalidad espec\u00edfica, pueden retirarlo en cualquier momento, sin que ello afecte a la licitud del tratamiento basado en el consentimiento previo a su retirada. En estos supuestos dejaremos de tratar los datos o, en su caso, dejaremos de hacerlo para esa finalidad en concreto, salvo por motivos leg\u00edtimos imperiosos, o el ejercicio o la defensa de posibles reclamaciones, o en aquellas excepciones establecidas en la normativa aplicable.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Todos los derechos mencionados pueden ejercerse dirigiendo la correspondiente solicitud, en la que se debe adjuntar un medio de identificaci\u00f3n, a contact@energystoragesolutions.com.<\/span><\/p>\n<p><span style=\"color: #ffffff;\">Frente a cualquier vulneraci\u00f3n de sus derechos, especialmente cuando no haya obtenido satisfacci\u00f3n en su ejercicio, un interesado puede presentar una reclamaci\u00f3n ante la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos (datos de contacto accesibles en\u00a0<a href=\"http:\/\/www.agpd.es\">www.agpd.es<\/a>).<\/span><\/p>\n<\/div><div class=\"fusion-clearfix\"><\/div><\/div><\/div><\/div><\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"100-width.php","meta":{"_exactmetrics_skip_tracking":false,"_exactmetrics_sitenote_active":false,"_exactmetrics_sitenote_note":"","_exactmetrics_sitenote_category":0},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v19.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Pol\u00edtica de Privacidad | E22 Energy Storage Solutions<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de Privacidad | E22 Energy Storage Solutions\" \/>\n<meta property=\"og:url\" content=\"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"E22 Energy Storage Solutions\" \/>\n<meta property=\"article:modified_time\" content=\"2024-11-14T09:57:09+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"7 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Organization\",\"@id\":\"https:\/\/energystoragesolutions.com\/#organization\",\"name\":\"E22 Energy Storage Solutions\",\"url\":\"https:\/\/energystoragesolutions.com\/\",\"sameAs\":[\"https:\/\/www.linkedin.com\/company\/energy-storage-solutions\/\"],\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\/\/energystoragesolutions.com\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/energystoragesolutions.com\/wp-content\/uploads\/2018\/10\/E22-energy-storage-logo.png\",\"contentUrl\":\"https:\/\/energystoragesolutions.com\/wp-content\/uploads\/2018\/10\/E22-energy-storage-logo.png\",\"width\":200,\"height\":54,\"caption\":\"E22 Energy Storage Solutions\"},\"image\":{\"@id\":\"https:\/\/energystoragesolutions.com\/#\/schema\/logo\/image\/\"}},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/energystoragesolutions.com\/#website\",\"url\":\"https:\/\/energystoragesolutions.com\/\",\"name\":\"E22 Energy Storage Solutions\",\"description\":\"BESS, Vanadium Redox Batteries and EPC of Energy Storage\",\"publisher\":{\"@id\":\"https:\/\/energystoragesolutions.com\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/energystoragesolutions.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/#webpage\",\"url\":\"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/\",\"name\":\"Pol\u00edtica de Privacidad | E22 Energy Storage Solutions\",\"isPartOf\":{\"@id\":\"https:\/\/energystoragesolutions.com\/#website\"},\"datePublished\":\"2021-01-20T11:58:28+00:00\",\"dateModified\":\"2024-11-14T09:57:09+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/energystoragesolutions.com\/es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de Privacidad\"}]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de Privacidad | E22 Energy Storage Solutions","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/","og_locale":"es_ES","og_type":"article","og_title":"Pol\u00edtica de Privacidad | E22 Energy Storage Solutions","og_url":"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/","og_site_name":"E22 Energy Storage Solutions","article_modified_time":"2024-11-14T09:57:09+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Tiempo de lectura":"7 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Organization","@id":"https:\/\/energystoragesolutions.com\/#organization","name":"E22 Energy Storage Solutions","url":"https:\/\/energystoragesolutions.com\/","sameAs":["https:\/\/www.linkedin.com\/company\/energy-storage-solutions\/"],"logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/energystoragesolutions.com\/#\/schema\/logo\/image\/","url":"https:\/\/energystoragesolutions.com\/wp-content\/uploads\/2018\/10\/E22-energy-storage-logo.png","contentUrl":"https:\/\/energystoragesolutions.com\/wp-content\/uploads\/2018\/10\/E22-energy-storage-logo.png","width":200,"height":54,"caption":"E22 Energy Storage Solutions"},"image":{"@id":"https:\/\/energystoragesolutions.com\/#\/schema\/logo\/image\/"}},{"@type":"WebSite","@id":"https:\/\/energystoragesolutions.com\/#website","url":"https:\/\/energystoragesolutions.com\/","name":"E22 Energy Storage Solutions","description":"BESS, Vanadium Redox Batteries and EPC of Energy Storage","publisher":{"@id":"https:\/\/energystoragesolutions.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/energystoragesolutions.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/#webpage","url":"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/","name":"Pol\u00edtica de Privacidad | E22 Energy Storage Solutions","isPartOf":{"@id":"https:\/\/energystoragesolutions.com\/#website"},"datePublished":"2021-01-20T11:58:28+00:00","dateModified":"2024-11-14T09:57:09+00:00","breadcrumb":{"@id":"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/energystoragesolutions.com\/es\/politica-de-privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/energystoragesolutions.com\/es\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de Privacidad"}]}]}},"_links":{"self":[{"href":"https:\/\/energystoragesolutions.com\/es\/wp-json\/wp\/v2\/pages\/2643"}],"collection":[{"href":"https:\/\/energystoragesolutions.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/energystoragesolutions.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/energystoragesolutions.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/energystoragesolutions.com\/es\/wp-json\/wp\/v2\/comments?post=2643"}],"version-history":[{"count":18,"href":"https:\/\/energystoragesolutions.com\/es\/wp-json\/wp\/v2\/pages\/2643\/revisions"}],"predecessor-version":[{"id":15216,"href":"https:\/\/energystoragesolutions.com\/es\/wp-json\/wp\/v2\/pages\/2643\/revisions\/15216"}],"wp:attachment":[{"href":"https:\/\/energystoragesolutions.com\/es\/wp-json\/wp\/v2\/media?parent=2643"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}